{"id":25962,"date":"2024-01-16T07:39:19","date_gmt":"2024-01-16T02:09:19","guid":{"rendered":"https:\/\/conexmetals.com\/product\/din-6325-m6-dowel-pins\/"},"modified":"2026-06-29T10:54:31","modified_gmt":"2026-06-29T05:24:31","slug":"din-6325-m6-dowel-pins","status":"publish","type":"product","link":"https:\/\/conexmetals.com\/es\/producto\/din-6325-m6-dowel-pins\/","title":{"rendered":"Pasadores Cil\u00edndricos m6 DIN 6325"},"content":{"rendered":"\n<table id=\"tablepress-186\" class=\"tablepress tablepress-id-186 tbody-has-connected-cells\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\"><strong>DIN 6325-M6 DOWEL PINS<\/strong><\/th><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">Diameter<\/td><td class=\"column-2\"><strong>0.8<\/strong><\/td><td class=\"column-3\"><strong>1<\/strong><\/td><td class=\"column-4\"><strong>1.5<\/strong><\/td><td class=\"column-5\"><strong>2<\/strong><\/td><td class=\"column-6\"><strong>2.5<\/strong><\/td><td class=\"column-7\"><strong>3<\/strong><\/td><td class=\"column-8\"><strong>4<\/strong><\/td><td class=\"column-9\"><strong>5<\/strong><\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">z<sub>2<\/sub>\u00a0\u00bb<\/td><td class=\"column-2\">0.06<\/td><td class=\"column-3\">0.08<\/td><td class=\"column-4\">0.12<\/td><td class=\"column-5\">0.18<\/td><td class=\"column-6\">0.25<\/td><td class=\"column-7\">0.3<\/td><td class=\"column-8\">0.4<\/td><td class=\"column-9\">0.5<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">z<sub>1<\/sub>\u00a0\u00bb<\/td><td class=\"column-2\">0.12<\/td><td class=\"column-3\">0.15<\/td><td class=\"column-4\">0.23<\/td><td class=\"column-5\">0.3<\/td><td class=\"column-6\">0.4<\/td><td class=\"column-7\">0.45<\/td><td class=\"column-8\">0.6<\/td><td class=\"column-9\">0.75<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">l<sub>1<\/sub><\/td><td class=\"column-2\">0.4<\/td><td class=\"column-3\">0.4<\/td><td class=\"column-4\">0.5<\/td><td class=\"column-5\">0.6<\/td><td class=\"column-6\">0.7<\/td><td class=\"column-7\">0.8<\/td><td class=\"column-8\">1<\/td><td class=\"column-9\">1.2<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">Length (mm)<\/td><td colspan=\"8\" class=\"column-2\">CON4<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">2<\/td><td class=\"column-2\">*<\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">3<\/td><td class=\"column-2\">*<\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">4<\/td><td class=\"column-2\">*<\/td><td class=\"column-3\">*<\/td><td class=\"column-4\">*<\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">5<\/td><td class=\"column-2\">*<\/td><td class=\"column-3\">*<\/td><td class=\"column-4\">*<\/td><td class=\"column-5\">S<\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">6<\/td><td class=\"column-2\">*<\/td><td class=\"column-3\">*<\/td><td class=\"column-4\">*<\/td><td class=\"column-5\">S<\/td><td class=\"column-6\">S<\/td><td class=\"column-7\">S<\/td><td class=\"column-8\">S<\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">8<\/td><td class=\"column-2\">*<\/td><td class=\"column-3\">S<\/td><td class=\"column-4\">S<\/td><td class=\"column-5\">S<\/td><td class=\"column-6\">S<\/td><td class=\"column-7\">S<\/td><td class=\"column-8\">S<\/td><td class=\"column-9\">S<\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">10<\/td><td class=\"column-2\"><\/td><td class=\"column-3\">*<\/td><td class=\"column-4\">*<\/td><td class=\"column-5\">S<\/td><td class=\"column-6\">S<\/td><td class=\"column-7\">S<\/td><td class=\"column-8\">S<\/td><td class=\"column-9\">S<\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">12<\/td><td class=\"column-2\"><\/td><td class=\"column-3\">S<\/td><td class=\"column-4\">S<\/td><td class=\"column-5\">S<\/td><td class=\"column-6\">S<\/td><td class=\"column-7\">S<\/td><td class=\"column-8\">S<\/td><td class=\"column-9\">S<\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">14<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\">*<\/td><td class=\"column-5\">S<\/td><td class=\"column-6\">S<\/td><td class=\"column-7\">S<\/td><td class=\"column-8\">S<\/td><td class=\"column-9\">S<\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">16<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\">*<\/td><td class=\"column-5\">S<\/td><td class=\"column-6\">S<\/td><td class=\"column-7\">S<\/td><td class=\"column-8\">S<\/td><td class=\"column-9\">S<\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\">18<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\">*<\/td><td class=\"column-5\">*<\/td><td class=\"column-6\">*<\/td><td class=\"column-7\">S<\/td><td class=\"column-8\">*<\/td><td class=\"column-9\">*<\/td>\n<\/tr>\n<tr class=\"row-18\">\n\t<td class=\"column-1\">20<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\">S<\/td><td class=\"column-5\">S<\/td><td class=\"column-6\">S<\/td><td class=\"column-7\">S<\/td><td class=\"column-8\">S<\/td><td class=\"column-9\">S<\/td>\n<\/tr>\n<tr class=\"row-19\">\n\t<td class=\"column-1\">22<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\">*<\/td><td class=\"column-5\">*<\/td><td class=\"column-6\">*<\/td><td class=\"column-7\">*<\/td><td class=\"column-8\">*<\/td><td class=\"column-9\">*<\/td>\n<\/tr>\n<tr class=\"row-20\">\n\t<td class=\"column-1\">24<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\">*<\/td><td class=\"column-5\">S<\/td><td class=\"column-6\">S<\/td><td class=\"column-7\">S<\/td><td class=\"column-8\">S<\/td><td class=\"column-9\">S<\/td>\n<\/tr>\n<tr class=\"row-21\">\n\t<td class=\"column-1\">28<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\">*<\/td><td class=\"column-5\">S<\/td><td class=\"column-6\">S<\/td><td class=\"column-7\">S<\/td><td class=\"column-8\">S<\/td><td class=\"column-9\">S<\/td>\n<\/tr>\n<tr class=\"row-22\">\n\t<td class=\"column-1\">30<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\">*<\/td><td class=\"column-5\">S<\/td><td class=\"column-6\">*<\/td><td class=\"column-7\">S<\/td><td class=\"column-8\">S<\/td><td class=\"column-9\">S<\/td>\n<\/tr>\n<tr class=\"row-23\">\n\t<td class=\"column-1\">32<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\">S<\/td><td class=\"column-6\">S<\/td><td class=\"column-7\">S<\/td><td class=\"column-8\">S<\/td><td class=\"column-9\">S<\/td>\n<\/tr>\n<tr class=\"row-24\">\n\t<td class=\"column-1\">34<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\">*<\/td><td class=\"column-7\">*<\/td><td class=\"column-8\">*<\/td><td class=\"column-9\">*<\/td>\n<\/tr>\n<tr class=\"row-25\">\n\t<td class=\"column-1\">36<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\">S<\/td><td class=\"column-5\">*<\/td><td class=\"column-6\">*<\/td><td class=\"column-7\">S<\/td><td class=\"column-8\">S<\/td><td class=\"column-9\">S<\/td>\n<\/tr>\n<tr class=\"row-26\">\n\t<td class=\"column-1\">40<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\">*<\/td><td class=\"column-5\">*<\/td><td class=\"column-6\">*<\/td><td class=\"column-7\">S<\/td><td class=\"column-8\">S<\/td><td class=\"column-9\">S<\/td>\n<\/tr>\n<tr class=\"row-27\">\n\t<td class=\"column-1\">45<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\">*<\/td><td class=\"column-7\">*<\/td><td class=\"column-8\">S<\/td><td class=\"column-9\">S<\/td>\n<\/tr>\n<tr class=\"row-28\">\n\t<td class=\"column-1\">50<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\">*<\/td><td class=\"column-7\">*<\/td><td class=\"column-8\">S<\/td><td class=\"column-9\">S<\/td>\n<\/tr>\n<tr class=\"row-29\">\n\t<td class=\"column-1\">55<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\">S<\/td>\n<\/tr>\n<tr class=\"row-30\">\n\t<td class=\"column-1\">60<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\">*<\/td><td class=\"column-8\">*<\/td><td class=\"column-9\">S<\/td>\n<\/tr>\n<tr class=\"row-31\">\n\t<td class=\"column-1\">80<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\">*<\/td><td class=\"column-9\">*<\/td>\n<\/tr>\n<tr class=\"row-32\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-33\">\n\t<td class=\"column-1\">Diameter<\/td><td class=\"column-2\"><strong>6<\/strong><\/td><td class=\"column-3\"><strong>8<\/strong><\/td><td class=\"column-4\"><strong>10<\/strong><\/td><td class=\"column-5\"><strong>12<\/strong><\/td><td class=\"column-6\"><strong>14<\/strong><\/td><td class=\"column-7\"><strong>16<\/strong><\/td><td class=\"column-8\"><strong>20<\/strong><\/td><td class=\"column-9\"><strong>25<\/strong><\/td>\n<\/tr>\n<tr class=\"row-34\">\n\t<td class=\"column-1\">z<sub>2<\/sub>\u00a0\u00bb<\/td><td class=\"column-2\">0.6<\/td><td class=\"column-3\">0.8<\/td><td class=\"column-4\">1<\/td><td class=\"column-5\">1.3<\/td><td class=\"column-6\">1.3<\/td><td class=\"column-7\">1.7<\/td><td class=\"column-8\">2<\/td><td class=\"column-9\">-<\/td>\n<\/tr>\n<tr class=\"row-35\">\n\t<td class=\"column-1\">z<sub>1<\/sub>\u00a0\u00bb<\/td><td class=\"column-2\">0.9<\/td><td class=\"column-3\">1.2<\/td><td class=\"column-4\">1.5<\/td><td class=\"column-5\">1.8<\/td><td class=\"column-6\">2<\/td><td class=\"column-7\">2.5<\/td><td class=\"column-8\">3<\/td><td class=\"column-9\">-<\/td>\n<\/tr>\n<tr class=\"row-36\">\n\t<td class=\"column-1\">l<sub>1<\/sub><\/td><td class=\"column-2\">1.5<\/td><td class=\"column-3\">1.8<\/td><td class=\"column-4\">2<\/td><td class=\"column-5\">2.5<\/td><td class=\"column-6\">2.5<\/td><td class=\"column-7\">3<\/td><td class=\"column-8\">4<\/td><td class=\"column-9\">-<\/td>\n<\/tr>\n<tr class=\"row-37\">\n\t<td class=\"column-1\">Length (mm)<\/td><td colspan=\"8\" class=\"column-2\">CON4<\/td>\n<\/tr>\n<tr class=\"row-38\">\n\t<td class=\"column-1\">10<\/td><td class=\"column-2\">S<\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-39\">\n\t<td class=\"column-1\">12<\/td><td class=\"column-2\">S<\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-40\">\n\t<td class=\"column-1\">14<\/td><td class=\"column-2\">S<\/td><td class=\"column-3\">S<\/td><td class=\"column-4\">S<\/td><td class=\"column-5\">*<\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-41\">\n\t<td class=\"column-1\">16<\/td><td class=\"column-2\">S<\/td><td class=\"column-3\">S<\/td><td class=\"column-4\">*<\/td><td class=\"column-5\">*<\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-42\">\n\t<td class=\"column-1\">18<\/td><td class=\"column-2\">*<\/td><td class=\"column-3\">*<\/td><td class=\"column-4\">*<\/td><td class=\"column-5\">*<\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-43\">\n\t<td class=\"column-1\">20<\/td><td class=\"column-2\">S<\/td><td class=\"column-3\">S<\/td><td class=\"column-4\">S<\/td><td class=\"column-5\">S<\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-44\">\n\t<td class=\"column-1\">22<\/td><td class=\"column-2\">*<\/td><td class=\"column-3\">*<\/td><td class=\"column-4\">*<\/td><td class=\"column-5\">*<\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-45\">\n\t<td class=\"column-1\">24<\/td><td class=\"column-2\">S<\/td><td class=\"column-3\">S<\/td><td class=\"column-4\">S<\/td><td class=\"column-5\">S<\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-46\">\n\t<td class=\"column-1\">28<\/td><td class=\"column-2\">S<\/td><td class=\"column-3\">S<\/td><td class=\"column-4\">S<\/td><td class=\"column-5\">S<\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-47\">\n\t<td class=\"column-1\">30<\/td><td class=\"column-2\">S<\/td><td class=\"column-3\">S<\/td><td class=\"column-4\">S<\/td><td class=\"column-5\">S<\/td><td class=\"column-6\"><\/td><td class=\"column-7\">S<\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-48\">\n\t<td class=\"column-1\">32<\/td><td class=\"column-2\">S<\/td><td class=\"column-3\">S<\/td><td class=\"column-4\">S<\/td><td class=\"column-5\">S<\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-49\">\n\t<td class=\"column-1\">34<\/td><td class=\"column-2\">*<\/td><td class=\"column-3\">*<\/td><td class=\"column-4\">*<\/td><td class=\"column-5\">*<\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-50\">\n\t<td class=\"column-1\">36<\/td><td class=\"column-2\">S<\/td><td class=\"column-3\">S<\/td><td class=\"column-4\">S<\/td><td class=\"column-5\">S<\/td><td class=\"column-6\"><\/td><td class=\"column-7\">S<\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-51\">\n\t<td class=\"column-1\">40<\/td><td class=\"column-2\">S<\/td><td class=\"column-3\">S<\/td><td class=\"column-4\">S<\/td><td class=\"column-5\">S<\/td><td class=\"column-6\">S<\/td><td class=\"column-7\">S<\/td><td class=\"column-8\">S<\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-52\">\n\t<td class=\"column-1\">45<\/td><td class=\"column-2\">S<\/td><td class=\"column-3\">S<\/td><td class=\"column-4\">S<\/td><td class=\"column-5\">S<\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-53\">\n\t<td class=\"column-1\">50<\/td><td class=\"column-2\">S<\/td><td class=\"column-3\">S<\/td><td class=\"column-4\">S<\/td><td class=\"column-5\">S<\/td><td class=\"column-6\">S<\/td><td class=\"column-7\">S<\/td><td class=\"column-8\">S<\/td><td class=\"column-9\">S<\/td>\n<\/tr>\n<tr class=\"row-54\">\n\t<td class=\"column-1\">55<\/td><td class=\"column-2\">S<\/td><td class=\"column-3\">S<\/td><td class=\"column-4\">S<\/td><td class=\"column-5\">S<\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-55\">\n\t<td class=\"column-1\">60<\/td><td class=\"column-2\">S<\/td><td class=\"column-3\">S<\/td><td class=\"column-4\">S<\/td><td class=\"column-5\">S<\/td><td class=\"column-6\">S<\/td><td class=\"column-7\">S<\/td><td class=\"column-8\">S<\/td><td class=\"column-9\">S<\/td>\n<\/tr>\n<tr class=\"row-56\">\n\t<td class=\"column-1\">70<\/td><td class=\"column-2\">S<\/td><td class=\"column-3\">S<\/td><td class=\"column-4\">S<\/td><td class=\"column-5\">S<\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-57\">\n\t<td class=\"column-1\">80<\/td><td class=\"column-2\">S<\/td><td class=\"column-3\">S<\/td><td class=\"column-4\">S<\/td><td class=\"column-5\">S<\/td><td class=\"column-6\">S<\/td><td class=\"column-7\">S<\/td><td class=\"column-8\">S<\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-58\">\n\t<td class=\"column-1\">90<\/td><td class=\"column-2\"><\/td><td class=\"column-3\">S<\/td><td class=\"column-4\">S<\/td><td class=\"column-5\">S<\/td><td class=\"column-6\">*<\/td><td class=\"column-7\">S<\/td><td class=\"column-8\">S<\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-59\">\n\t<td class=\"column-1\">100<\/td><td class=\"column-2\"><\/td><td class=\"column-3\">S<\/td><td class=\"column-4\">S<\/td><td class=\"column-5\">S<\/td><td class=\"column-6\">*<\/td><td class=\"column-7\">S<\/td><td class=\"column-8\">S<\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-60\">\n\t<td class=\"column-1\">120<\/td><td class=\"column-2\"><\/td><td class=\"column-3\">S<\/td><td class=\"column-4\">*<\/td><td class=\"column-5\">*<\/td><td class=\"column-6\">*<\/td><td class=\"column-7\">S<\/td><td class=\"column-8\">S<\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-61\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-62\">\n\t<td colspan=\"2\" class=\"column-1\"><strong>Nominal Dimension<\/strong><\/td><td rowspan=\"2\" class=\"column-3\"><strong>h6 \"minus\" Tolerance<\/strong><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-63\">\n\t<td class=\"column-1\"><strong>over<\/strong><\/td><td class=\"column-2\"><strong>to<\/strong><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-64\">\n\t<td class=\"column-1\">0<\/td><td class=\"column-2\">1<\/td><td class=\"column-3\">0 -0.006<\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-65\">\n\t<td class=\"column-1\">1<\/td><td class=\"column-2\">3<\/td><td class=\"column-3\">0 -0.006<\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-66\">\n\t<td class=\"column-1\">3<\/td><td class=\"column-2\">6<\/td><td class=\"column-3\">0 -0.008<\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-67\">\n\t<td class=\"column-1\">6<\/td><td class=\"column-2\">10<\/td><td class=\"column-3\">0 -0.009<\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-68\">\n\t<td class=\"column-1\">10<\/td><td class=\"column-2\">18<\/td><td class=\"column-3\">0 -0.011<\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<tr class=\"row-69\">\n\t<td colspan=\"9\" class=\"column-1\"><\/td>\n<\/tr>\n<tr class=\"row-70\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n","protected":false},"excerpt":{"rendered":"[table id=186 \/]\n","protected":false},"featured_media":8752,"template":"","meta":[],"product_brand":[],"product_cat":[308],"product_tag":[],"class_list":{"0":"post-25962","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-sin-categorizar","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pasadores Cil\u00edndricos m6 DIN 6325<\/title>\n<meta name=\"description\" content=\"Conex Metals, a global leader in metal manufacturing and export for 34 years, delivers excellence worldwide. Specializing in high-quality non-ferrous metal components such as Brass Fittings, Brass Parts, Copper Parts, and Brass Plumbing Fittings. Experience precision and innovation with Conex Metals.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/conexmetals.com\/es\/producto\/din-6325-m6-dowel-pins\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/conexmetals.com\\\/es\\\/producto\\\/din-6325-m6-dowel-pins\\\/\",\"url\":\"https:\\\/\\\/conexmetals.com\\\/es\\\/producto\\\/din-6325-m6-dowel-pins\\\/\",\"name\":\"Pasadores Cil\u00edndricos m6 DIN 6325\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/conexmetals.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/conexmetals.com\\\/es\\\/producto\\\/din-6325-m6-dowel-pins\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/conexmetals.com\\\/es\\\/producto\\\/din-6325-m6-dowel-pins\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/conexmetals.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/spec_6325.jpg\",\"datePublished\":\"2024-01-16T02:09:19+00:00\",\"dateModified\":\"2026-06-29T05:24:31+00:00\",\"description\":\"Conex Metals, a global leader in metal manufacturing and export for 34 years, delivers excellence worldwide. Specializing in high-quality non-ferrous metal components such as Brass Fittings, Brass Parts, Copper Parts, and Brass Plumbing Fittings. Experience precision and innovation with Conex Metals.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/conexmetals.com\\\/es\\\/producto\\\/din-6325-m6-dowel-pins\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/conexmetals.com\\\/es\\\/producto\\\/din-6325-m6-dowel-pins\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/conexmetals.com\\\/es\\\/producto\\\/din-6325-m6-dowel-pins\\\/#primaryimage\",\"url\":\"https:\\\/\\\/conexmetals.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/spec_6325.jpg\",\"contentUrl\":\"https:\\\/\\\/conexmetals.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/spec_6325.jpg\",\"width\":313,\"height\":313},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/conexmetals.com\\\/es\\\/producto\\\/din-6325-m6-dowel-pins\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/conexmetals.com\\\/es\\\/hogar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/conexmetals.com\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pasadores Cil\u00edndricos m6 DIN 6325\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/conexmetals.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/conexmetals.com\\\/es\\\/\",\"name\":\"Conex Metals Brass Fittings Brass Parts Copper Parts Brass Components Brass Plumbing Fittings India\",\"description\":\"Manufacturer of Bronze Fittings casting Copper Brass parts components\",\"publisher\":{\"@id\":\"https:\\\/\\\/conexmetals.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/conexmetals.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/conexmetals.com\\\/es\\\/#organization\",\"name\":\"Conex Metals\",\"url\":\"https:\\\/\\\/conexmetals.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/conexmetals.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/conexmetals.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/conex-metals-logo.webp\",\"contentUrl\":\"https:\\\/\\\/conexmetals.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/conex-metals-logo.webp\",\"width\":300,\"height\":121,\"caption\":\"Conex Metals\"},\"image\":{\"@id\":\"https:\\\/\\\/conexmetals.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/conexbrass\",\"https:\\\/\\\/x.com\\\/conexindia\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/conex-metals-india\\\/\",\"https:\\\/\\\/www.instagram.com\\\/conexindia\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pasadores Cil\u00edndricos m6 DIN 6325","description":"Conex Metals, a global leader in metal manufacturing and export for 34 years, delivers excellence worldwide. Specializing in high-quality non-ferrous metal components such as Brass Fittings, Brass Parts, Copper Parts, and Brass Plumbing Fittings. Experience precision and innovation with Conex Metals.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/conexmetals.com\/es\/producto\/din-6325-m6-dowel-pins\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/conexmetals.com\/es\/producto\/din-6325-m6-dowel-pins\/","url":"https:\/\/conexmetals.com\/es\/producto\/din-6325-m6-dowel-pins\/","name":"Pasadores Cil\u00edndricos m6 DIN 6325","isPartOf":{"@id":"https:\/\/conexmetals.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/conexmetals.com\/es\/producto\/din-6325-m6-dowel-pins\/#primaryimage"},"image":{"@id":"https:\/\/conexmetals.com\/es\/producto\/din-6325-m6-dowel-pins\/#primaryimage"},"thumbnailUrl":"https:\/\/conexmetals.com\/wp-content\/uploads\/2023\/12\/spec_6325.jpg","datePublished":"2024-01-16T02:09:19+00:00","dateModified":"2026-06-29T05:24:31+00:00","description":"Conex Metals, a global leader in metal manufacturing and export for 34 years, delivers excellence worldwide. Specializing in high-quality non-ferrous metal components such as Brass Fittings, Brass Parts, Copper Parts, and Brass Plumbing Fittings. Experience precision and innovation with Conex Metals.","breadcrumb":{"@id":"https:\/\/conexmetals.com\/es\/producto\/din-6325-m6-dowel-pins\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/conexmetals.com\/es\/producto\/din-6325-m6-dowel-pins\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/conexmetals.com\/es\/producto\/din-6325-m6-dowel-pins\/#primaryimage","url":"https:\/\/conexmetals.com\/wp-content\/uploads\/2023\/12\/spec_6325.jpg","contentUrl":"https:\/\/conexmetals.com\/wp-content\/uploads\/2023\/12\/spec_6325.jpg","width":313,"height":313},{"@type":"BreadcrumbList","@id":"https:\/\/conexmetals.com\/es\/producto\/din-6325-m6-dowel-pins\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/conexmetals.com\/es\/hogar\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/conexmetals.com\/products\/"},{"@type":"ListItem","position":3,"name":"Pasadores Cil\u00edndricos m6 DIN 6325"}]},{"@type":"WebSite","@id":"https:\/\/conexmetals.com\/es\/#website","url":"https:\/\/conexmetals.com\/es\/","name":"Conex Metals Brass Fittings Brass Parts Copper Parts Brass Components Brass Plumbing Fittings India","description":"Manufacturer of Bronze Fittings casting Copper Brass parts components","publisher":{"@id":"https:\/\/conexmetals.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/conexmetals.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/conexmetals.com\/es\/#organization","name":"Conex Metals","url":"https:\/\/conexmetals.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/conexmetals.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/conexmetals.com\/wp-content\/uploads\/2024\/03\/conex-metals-logo.webp","contentUrl":"https:\/\/conexmetals.com\/wp-content\/uploads\/2024\/03\/conex-metals-logo.webp","width":300,"height":121,"caption":"Conex Metals"},"image":{"@id":"https:\/\/conexmetals.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/conexbrass","https:\/\/x.com\/conexindia","https:\/\/www.linkedin.com\/company\/conex-metals-india\/","https:\/\/www.instagram.com\/conexindia\/"]}]}},"_links":{"self":[{"href":"https:\/\/conexmetals.com\/es\/wp-json\/wp\/v2\/product\/25962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexmetals.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/conexmetals.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexmetals.com\/es\/wp-json\/wp\/v2\/media\/8752"}],"wp:attachment":[{"href":"https:\/\/conexmetals.com\/es\/wp-json\/wp\/v2\/media?parent=25962"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/conexmetals.com\/es\/wp-json\/wp\/v2\/product_brand?post=25962"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/conexmetals.com\/es\/wp-json\/wp\/v2\/product_cat?post=25962"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/conexmetals.com\/es\/wp-json\/wp\/v2\/product_tag?post=25962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}