{"id":26143,"date":"2024-01-13T11:23:49","date_gmt":"2024-01-13T05:53:49","guid":{"rendered":"https:\/\/conexmetals.com\/product\/din-963-slotted-flat-head-machine-screw\/"},"modified":"2026-06-29T10:54:39","modified_gmt":"2026-06-29T05:24:39","slug":"din-963-slotted-flat-head-machine-screw","status":"publish","type":"product","link":"https:\/\/conexmetals.com\/es\/producto\/din-963-slotted-flat-head-machine-screw\/","title":{"rendered":"Tornillo de M\u00e1quina con Cabeza Plana Ranurado DIN 963"},"content":{"rendered":"\n<table id=\"tablepress-134\" class=\"tablepress tablepress-id-134 resizing-table tbody-has-connected-cells\">\n<thead>\n<tr class=\"row-1\">\n\t<th colspan=\"16\" class=\"column-1\"><strong>DIN 963 SLOTTED FLAT HEAD MACHINE SCREWS BRASS\u00a0 SLOTTED CSK SCREWS<\/strong><\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\"><strong>Diameter<\/strong><\/td><td class=\"column-2\"><strong>CON 1.6<\/strong><\/td><td class=\"column-3\"><strong>CON 2<\/strong><\/td><td class=\"column-4\"><strong>CON 2.2<\/strong><\/td><td class=\"column-5\"><strong>CON 2.3<\/strong><\/td><td class=\"column-6\"><strong>CON 2.5<\/strong><\/td><td class=\"column-7\"><strong>CON 2.6<\/strong><\/td><td class=\"column-8\"><strong>CON 3<\/strong><\/td><td class=\"column-9\"><strong>CON 3.5<\/strong><\/td><td class=\"column-10\"><strong>CON 4<\/strong><\/td><td class=\"column-11\"><strong>CON 5<\/strong><\/td><td class=\"column-12\"><strong>CON 6<\/strong><\/td><td class=\"column-13\"><strong>CON 8<\/strong><\/td><td class=\"column-14\"><strong>CON 10<\/strong><\/td><td class=\"column-15\"><strong>CON 12<\/strong><\/td><td class=\"column-16\"><strong>CON 16<\/strong><\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">t<\/td><td class=\"column-2\">0.32<\/td><td class=\"column-3\">0.4<\/td><td class=\"column-4\">0.4<\/td><td class=\"column-5\">0.4<\/td><td class=\"column-6\">0.5<\/td><td class=\"column-7\">0.5<\/td><td class=\"column-8\">0.6<\/td><td class=\"column-9\">0.7<\/td><td class=\"column-10\">0.8<\/td><td class=\"column-11\">1<\/td><td class=\"column-12\">1.2<\/td><td class=\"column-13\">1.6<\/td><td class=\"column-14\">2<\/td><td class=\"column-15\">2.4<\/td><td class=\"column-16\">3.2<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">n<\/td><td class=\"column-2\">0.4<\/td><td class=\"column-3\">0.5<\/td><td class=\"column-4\">0.6<\/td><td class=\"column-5\">0.6<\/td><td class=\"column-6\">0.6<\/td><td class=\"column-7\">0.6<\/td><td class=\"column-8\">0.8<\/td><td class=\"column-9\">0.8<\/td><td class=\"column-10\">1<\/td><td class=\"column-11\">1.2<\/td><td class=\"column-12\">1.6<\/td><td class=\"column-13\">2<\/td><td class=\"column-14\">2.5<\/td><td class=\"column-15\">3<\/td><td class=\"column-16\">4<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">k<\/td><td class=\"column-2\">0.96<\/td><td class=\"column-3\">1.2<\/td><td class=\"column-4\">1.3<\/td><td class=\"column-5\">1.3<\/td><td class=\"column-6\">1.5<\/td><td class=\"column-7\">1.5<\/td><td class=\"column-8\">1.65<\/td><td class=\"column-9\">1.93<\/td><td class=\"column-10\">2.2 <\/td><td class=\"column-11\">2.5<\/td><td class=\"column-12\">3<\/td><td class=\"column-13\">4<\/td><td class=\"column-14\">5<\/td><td class=\"column-15\">6<\/td><td class=\"column-16\">8<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">d<sub>1<\/sub><\/td><td class=\"column-2\">3<\/td><td class=\"column-3\">3.8<\/td><td class=\"column-4\">4.2<\/td><td class=\"column-5\">4.5<\/td><td class=\"column-6\">4.7<\/td><td class=\"column-7\">4.7<\/td><td class=\"column-8\">5.6<\/td><td class=\"column-9\">6.5<\/td><td class=\"column-10\">7.5<\/td><td class=\"column-11\">9.2<\/td><td class=\"column-12\">11<\/td><td class=\"column-13\">14.5<\/td><td class=\"column-14\">18<\/td><td class=\"column-15\">22<\/td><td class=\"column-16\">29<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">Length (mm)<\/td><td colspan=\"15\" class=\"column-2\">M030<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">2<\/td><td class=\"column-2\">*<\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td><td class=\"column-13\"><\/td><td class=\"column-14\"><\/td><td class=\"column-15\"><\/td><td class=\"column-16\"><\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">3<\/td><td class=\"column-2\">*<\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td><td class=\"column-13\"><\/td><td class=\"column-14\"><\/td><td class=\"column-15\"><\/td><td class=\"column-16\"><\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">4<\/td><td class=\"column-2\">*<\/td><td class=\"column-3\">S<\/td><td class=\"column-4\">*<\/td><td class=\"column-5\">*<\/td><td class=\"column-6\">S<\/td><td class=\"column-7\">*<\/td><td class=\"column-8\">S<\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td><td class=\"column-13\"><\/td><td class=\"column-14\"><\/td><td class=\"column-15\"><\/td><td class=\"column-16\"><\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">5<\/td><td class=\"column-2\">*<\/td><td class=\"column-3\">S<\/td><td class=\"column-4\">*<\/td><td class=\"column-5\">*<\/td><td class=\"column-6\">S<\/td><td class=\"column-7\">*<\/td><td class=\"column-8\">S<\/td><td class=\"column-9\">*<\/td><td class=\"column-10\">S<\/td><td class=\"column-11\"><\/td><td class=\"column-12\"><\/td><td class=\"column-13\"><\/td><td class=\"column-14\"><\/td><td class=\"column-15\"><\/td><td class=\"column-16\"><\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">6<\/td><td class=\"column-2\">*<\/td><td class=\"column-3\">S<\/td><td class=\"column-4\">*<\/td><td class=\"column-5\">*<\/td><td class=\"column-6\">S<\/td><td class=\"column-7\">*<\/td><td class=\"column-8\">S<\/td><td class=\"column-9\">*<\/td><td class=\"column-10\">S<\/td><td class=\"column-11\">S<\/td><td class=\"column-12\"><\/td><td class=\"column-13\"><\/td><td class=\"column-14\"><\/td><td class=\"column-15\"><\/td><td class=\"column-16\"><\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">8<\/td><td class=\"column-2\">*<\/td><td class=\"column-3\">S<\/td><td class=\"column-4\">*<\/td><td class=\"column-5\">*<\/td><td class=\"column-6\">S<\/td><td class=\"column-7\">*<\/td><td class=\"column-8\">S<\/td><td class=\"column-9\">*<\/td><td class=\"column-10\">S<\/td><td class=\"column-11\">S<\/td><td class=\"column-12\">S<\/td><td class=\"column-13\"><\/td><td class=\"column-14\"><\/td><td class=\"column-15\"><\/td><td class=\"column-16\"><\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">10<\/td><td class=\"column-2\">*<\/td><td class=\"column-3\">S<\/td><td class=\"column-4\">*<\/td><td class=\"column-5\">*<\/td><td class=\"column-6\">S<\/td><td class=\"column-7\">*<\/td><td class=\"column-8\">S<\/td><td class=\"column-9\">*<\/td><td class=\"column-10\">S<\/td><td class=\"column-11\">S<\/td><td class=\"column-12\">S<\/td><td class=\"column-13\"><\/td><td class=\"column-14\"><\/td><td class=\"column-15\"><\/td><td class=\"column-16\"><\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">12<\/td><td class=\"column-2\">*<\/td><td class=\"column-3\">S<\/td><td class=\"column-4\">*<\/td><td class=\"column-5\">*<\/td><td class=\"column-6\">S<\/td><td class=\"column-7\">*<\/td><td class=\"column-8\">S<\/td><td class=\"column-9\">*<\/td><td class=\"column-10\">S<\/td><td class=\"column-11\">S<\/td><td class=\"column-12\">S<\/td><td class=\"column-13\">*<\/td><td class=\"column-14\"><\/td><td class=\"column-15\"><\/td><td class=\"column-16\"><\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">14<\/td><td class=\"column-2\"><\/td><td class=\"column-3\">*<\/td><td class=\"column-4\">*<\/td><td class=\"column-5\">*<\/td><td class=\"column-6\">*<\/td><td class=\"column-7\">*<\/td><td class=\"column-8\">*<\/td><td class=\"column-9\">*<\/td><td class=\"column-10\">S<\/td><td class=\"column-11\">S<\/td><td class=\"column-12\">S<\/td><td class=\"column-13\">*<\/td><td class=\"column-14\">*<\/td><td class=\"column-15\"><\/td><td class=\"column-16\"><\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\">16<\/td><td class=\"column-2\"><\/td><td class=\"column-3\">S<\/td><td class=\"column-4\">*<\/td><td class=\"column-5\">*<\/td><td class=\"column-6\">S<\/td><td class=\"column-7\">*<\/td><td class=\"column-8\">S<\/td><td class=\"column-9\">*<\/td><td class=\"column-10\">S<\/td><td class=\"column-11\">S<\/td><td class=\"column-12\">S<\/td><td class=\"column-13\">S<\/td><td class=\"column-14\">S<\/td><td class=\"column-15\"><\/td><td class=\"column-16\"><\/td>\n<\/tr>\n<tr class=\"row-18\">\n\t<td class=\"column-1\">18<\/td><td class=\"column-2\"><\/td><td class=\"column-3\">*<\/td><td class=\"column-4\">*<\/td><td class=\"column-5\">*<\/td><td class=\"column-6\">*<\/td><td class=\"column-7\">*<\/td><td class=\"column-8\">*<\/td><td class=\"column-9\">*<\/td><td class=\"column-10\">S<\/td><td class=\"column-11\">S<\/td><td class=\"column-12\">S<\/td><td class=\"column-13\">*<\/td><td class=\"column-14\">*<\/td><td class=\"column-15\"><\/td><td class=\"column-16\"><\/td>\n<\/tr>\n<tr class=\"row-19\">\n\t<td class=\"column-1\">20<\/td><td class=\"column-2\"><\/td><td class=\"column-3\">S<\/td><td class=\"column-4\">*<\/td><td class=\"column-5\">*<\/td><td class=\"column-6\">S<\/td><td class=\"column-7\">*<\/td><td class=\"column-8\">S<\/td><td class=\"column-9\">*<\/td><td class=\"column-10\">S<\/td><td class=\"column-11\">S<\/td><td class=\"column-12\">S<\/td><td class=\"column-13\">S<\/td><td class=\"column-14\">S<\/td><td class=\"column-15\">*<\/td><td class=\"column-16\"><\/td>\n<\/tr>\n<tr class=\"row-20\">\n\t<td class=\"column-1\">22<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\">S<\/td><td class=\"column-7\">*<\/td><td class=\"column-8\">*<\/td><td class=\"column-9\">*<\/td><td class=\"column-10\">*<\/td><td class=\"column-11\">*<\/td><td class=\"column-12\">*<\/td><td class=\"column-13\">*<\/td><td class=\"column-14\">*<\/td><td class=\"column-15\"><\/td><td class=\"column-16\"><\/td>\n<\/tr>\n<tr class=\"row-21\">\n\t<td class=\"column-1\">25<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\">*<\/td><td class=\"column-7\">*<\/td><td class=\"column-8\">S<\/td><td class=\"column-9\">*<\/td><td class=\"column-10\">S<\/td><td class=\"column-11\">S<\/td><td class=\"column-12\">S<\/td><td class=\"column-13\">S<\/td><td class=\"column-14\">S<\/td><td class=\"column-15\">*<\/td><td class=\"column-16\">*<\/td>\n<\/tr>\n<tr class=\"row-22\">\n\t<td class=\"column-1\">28<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\">*<\/td><td class=\"column-12\">*<\/td><td class=\"column-13\">*<\/td><td class=\"column-14\">*<\/td><td class=\"column-15\"><\/td><td class=\"column-16\"><\/td>\n<\/tr>\n<tr class=\"row-23\">\n\t<td class=\"column-1\">30<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\">*<\/td><td class=\"column-7\">*<\/td><td class=\"column-8\">S<\/td><td class=\"column-9\">*<\/td><td class=\"column-10\">S<\/td><td class=\"column-11\">S<\/td><td class=\"column-12\">S<\/td><td class=\"column-13\">S<\/td><td class=\"column-14\">S<\/td><td class=\"column-15\">*<\/td><td class=\"column-16\">*<\/td>\n<\/tr>\n<tr class=\"row-24\">\n\t<td class=\"column-1\">35<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\">S<\/td><td class=\"column-9\">*<\/td><td class=\"column-10\">S<\/td><td class=\"column-11\">S<\/td><td class=\"column-12\">S<\/td><td class=\"column-13\">S<\/td><td class=\"column-14\">S<\/td><td class=\"column-15\">*<\/td><td class=\"column-16\">*<\/td>\n<\/tr>\n<tr class=\"row-25\">\n\t<td class=\"column-1\">40<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\">S<\/td><td class=\"column-9\">*<\/td><td class=\"column-10\">S<\/td><td class=\"column-11\">S<\/td><td class=\"column-12\">S<\/td><td class=\"column-13\">S<\/td><td class=\"column-14\">S<\/td><td class=\"column-15\">*<\/td><td class=\"column-16\">*<\/td>\n<\/tr>\n<tr class=\"row-26\">\n\t<td class=\"column-1\">45<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\">S<\/td><td class=\"column-9\"><\/td><td class=\"column-10\">S<\/td><td class=\"column-11\">S<\/td><td class=\"column-12\">S<\/td><td class=\"column-13\">S<\/td><td class=\"column-14\">S<\/td><td class=\"column-15\">*<\/td><td class=\"column-16\">*<\/td>\n<\/tr>\n<tr class=\"row-27\">\n\t<td class=\"column-1\">50<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\">S<\/td><td class=\"column-9\"><\/td><td class=\"column-10\">S<\/td><td class=\"column-11\">S<\/td><td class=\"column-12\">S<\/td><td class=\"column-13\">S<\/td><td class=\"column-14\">S<\/td><td class=\"column-15\">*<\/td><td class=\"column-16\">*<\/td>\n<\/tr>\n<tr class=\"row-28\">\n\t<td class=\"column-1\">55<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td><td class=\"column-10\">*<\/td><td class=\"column-11\">S<\/td><td class=\"column-12\">S<\/td><td class=\"column-13\">*<\/td><td class=\"column-14\">*<\/td><td class=\"column-15\"><\/td><td class=\"column-16\"><\/td>\n<\/tr>\n<tr class=\"row-29\">\n\t<td class=\"column-1\">60<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\">S<\/td><td class=\"column-9\"><\/td><td class=\"column-10\">*<\/td><td class=\"column-11\">S<\/td><td class=\"column-12\">S<\/td><td class=\"column-13\">*<\/td><td class=\"column-14\">S<\/td><td class=\"column-15\">*<\/td><td class=\"column-16\">*<\/td>\n<\/tr>\n<tr class=\"row-30\">\n\t<td class=\"column-1\">65<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td><td class=\"column-10\">*<\/td><td class=\"column-11\">*<\/td><td class=\"column-12\">*<\/td><td class=\"column-13\">*<\/td><td class=\"column-14\">*<\/td><td class=\"column-15\"><\/td><td class=\"column-16\"><\/td>\n<\/tr>\n<tr class=\"row-31\">\n\t<td class=\"column-1\">70<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td><td class=\"column-10\">*<\/td><td class=\"column-11\">*<\/td><td class=\"column-12\">S<\/td><td class=\"column-13\">*<\/td><td class=\"column-14\">*<\/td><td class=\"column-15\">*<\/td><td class=\"column-16\">*<\/td>\n<\/tr>\n<tr class=\"row-32\">\n\t<td class=\"column-1\">75<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td><td class=\"column-10\">*<\/td><td class=\"column-11\">*<\/td><td class=\"column-12\">*<\/td><td class=\"column-13\">*<\/td><td class=\"column-14\">*<\/td><td class=\"column-15\"><\/td><td class=\"column-16\"><\/td>\n<\/tr>\n<tr class=\"row-33\">\n\t<td class=\"column-1\">80<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td><td class=\"column-10\">*<\/td><td class=\"column-11\">S<\/td><td class=\"column-12\">*<\/td><td class=\"column-13\">*<\/td><td class=\"column-14\">*<\/td><td class=\"column-15\">*<\/td><td class=\"column-16\">*<\/td>\n<\/tr>\n<tr class=\"row-34\">\n\t<td class=\"column-1\">90<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\">*<\/td><td class=\"column-12\">*<\/td><td class=\"column-13\">*<\/td><td class=\"column-14\">*<\/td><td class=\"column-15\">*<\/td><td class=\"column-16\">*<\/td>\n<\/tr>\n<tr class=\"row-35\">\n\t<td class=\"column-1\">100<\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td><td class=\"column-9\"><\/td><td class=\"column-10\"><\/td><td class=\"column-11\">S<\/td><td class=\"column-12\">S<\/td><td class=\"column-13\">*<\/td><td class=\"column-14\">*<\/td><td class=\"column-15\">*<\/td><td class=\"column-16\">*<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-134 from cache -->\n","protected":false},"excerpt":{"rendered":"[table id=134 \/]\n","protected":false},"featured_media":8727,"template":"","meta":[],"product_brand":[],"product_cat":[308],"product_tag":[],"class_list":{"0":"post-26143","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-sin-categorizar","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tornillo de M\u00e1quina con Cabeza Plana Ranurado DIN 963<\/title>\n<meta name=\"description\" content=\"Conex Metals, a global leader in metal manufacturing and export for 34 years, delivers excellence worldwide. Specializing in high-quality non-ferrous metal components such as Brass Fittings, Brass Parts, Copper Parts, and Brass Plumbing Fittings. Experience precision and innovation with Conex Metals.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/conexmetals.com\/es\/producto\/din-963-slotted-flat-head-machine-screw\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/conexmetals.com\\\/es\\\/producto\\\/din-963-slotted-flat-head-machine-screw\\\/\",\"url\":\"https:\\\/\\\/conexmetals.com\\\/es\\\/producto\\\/din-963-slotted-flat-head-machine-screw\\\/\",\"name\":\"Tornillo de M\u00e1quina con Cabeza Plana Ranurado DIN 963\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/conexmetals.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/conexmetals.com\\\/es\\\/producto\\\/din-963-slotted-flat-head-machine-screw\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/conexmetals.com\\\/es\\\/producto\\\/din-963-slotted-flat-head-machine-screw\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/conexmetals.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/spec_963.jpg\",\"datePublished\":\"2024-01-13T05:53:49+00:00\",\"dateModified\":\"2026-06-29T05:24:39+00:00\",\"description\":\"Conex Metals, a global leader in metal manufacturing and export for 34 years, delivers excellence worldwide. Specializing in high-quality non-ferrous metal components such as Brass Fittings, Brass Parts, Copper Parts, and Brass Plumbing Fittings. Experience precision and innovation with Conex Metals.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/conexmetals.com\\\/es\\\/producto\\\/din-963-slotted-flat-head-machine-screw\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/conexmetals.com\\\/es\\\/producto\\\/din-963-slotted-flat-head-machine-screw\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/conexmetals.com\\\/es\\\/producto\\\/din-963-slotted-flat-head-machine-screw\\\/#primaryimage\",\"url\":\"https:\\\/\\\/conexmetals.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/spec_963.jpg\",\"contentUrl\":\"https:\\\/\\\/conexmetals.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/spec_963.jpg\",\"width\":320,\"height\":320},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/conexmetals.com\\\/es\\\/producto\\\/din-963-slotted-flat-head-machine-screw\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/conexmetals.com\\\/es\\\/hogar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/conexmetals.com\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tornillo de M\u00e1quina con Cabeza Plana Ranurado DIN 963\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/conexmetals.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/conexmetals.com\\\/es\\\/\",\"name\":\"Conex Metals Brass Fittings Brass Parts Copper Parts Brass Components Brass Plumbing Fittings India\",\"description\":\"Manufacturer of Bronze Fittings casting Copper Brass parts components\",\"publisher\":{\"@id\":\"https:\\\/\\\/conexmetals.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/conexmetals.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/conexmetals.com\\\/es\\\/#organization\",\"name\":\"Conex Metals\",\"url\":\"https:\\\/\\\/conexmetals.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/conexmetals.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/conexmetals.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/conex-metals-logo.webp\",\"contentUrl\":\"https:\\\/\\\/conexmetals.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/conex-metals-logo.webp\",\"width\":300,\"height\":121,\"caption\":\"Conex Metals\"},\"image\":{\"@id\":\"https:\\\/\\\/conexmetals.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/conexbrass\",\"https:\\\/\\\/x.com\\\/conexindia\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/conex-metals-india\\\/\",\"https:\\\/\\\/www.instagram.com\\\/conexindia\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tornillo de M\u00e1quina con Cabeza Plana Ranurado DIN 963","description":"Conex Metals, a global leader in metal manufacturing and export for 34 years, delivers excellence worldwide. Specializing in high-quality non-ferrous metal components such as Brass Fittings, Brass Parts, Copper Parts, and Brass Plumbing Fittings. Experience precision and innovation with Conex Metals.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/conexmetals.com\/es\/producto\/din-963-slotted-flat-head-machine-screw\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/conexmetals.com\/es\/producto\/din-963-slotted-flat-head-machine-screw\/","url":"https:\/\/conexmetals.com\/es\/producto\/din-963-slotted-flat-head-machine-screw\/","name":"Tornillo de M\u00e1quina con Cabeza Plana Ranurado DIN 963","isPartOf":{"@id":"https:\/\/conexmetals.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/conexmetals.com\/es\/producto\/din-963-slotted-flat-head-machine-screw\/#primaryimage"},"image":{"@id":"https:\/\/conexmetals.com\/es\/producto\/din-963-slotted-flat-head-machine-screw\/#primaryimage"},"thumbnailUrl":"https:\/\/conexmetals.com\/wp-content\/uploads\/2023\/12\/spec_963.jpg","datePublished":"2024-01-13T05:53:49+00:00","dateModified":"2026-06-29T05:24:39+00:00","description":"Conex Metals, a global leader in metal manufacturing and export for 34 years, delivers excellence worldwide. Specializing in high-quality non-ferrous metal components such as Brass Fittings, Brass Parts, Copper Parts, and Brass Plumbing Fittings. Experience precision and innovation with Conex Metals.","breadcrumb":{"@id":"https:\/\/conexmetals.com\/es\/producto\/din-963-slotted-flat-head-machine-screw\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/conexmetals.com\/es\/producto\/din-963-slotted-flat-head-machine-screw\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/conexmetals.com\/es\/producto\/din-963-slotted-flat-head-machine-screw\/#primaryimage","url":"https:\/\/conexmetals.com\/wp-content\/uploads\/2023\/12\/spec_963.jpg","contentUrl":"https:\/\/conexmetals.com\/wp-content\/uploads\/2023\/12\/spec_963.jpg","width":320,"height":320},{"@type":"BreadcrumbList","@id":"https:\/\/conexmetals.com\/es\/producto\/din-963-slotted-flat-head-machine-screw\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/conexmetals.com\/es\/hogar\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/conexmetals.com\/products\/"},{"@type":"ListItem","position":3,"name":"Tornillo de M\u00e1quina con Cabeza Plana Ranurado DIN 963"}]},{"@type":"WebSite","@id":"https:\/\/conexmetals.com\/es\/#website","url":"https:\/\/conexmetals.com\/es\/","name":"Conex Metals Brass Fittings Brass Parts Copper Parts Brass Components Brass Plumbing Fittings India","description":"Manufacturer of Bronze Fittings casting Copper Brass parts components","publisher":{"@id":"https:\/\/conexmetals.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/conexmetals.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/conexmetals.com\/es\/#organization","name":"Conex Metals","url":"https:\/\/conexmetals.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/conexmetals.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/conexmetals.com\/wp-content\/uploads\/2024\/03\/conex-metals-logo.webp","contentUrl":"https:\/\/conexmetals.com\/wp-content\/uploads\/2024\/03\/conex-metals-logo.webp","width":300,"height":121,"caption":"Conex Metals"},"image":{"@id":"https:\/\/conexmetals.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/conexbrass","https:\/\/x.com\/conexindia","https:\/\/www.linkedin.com\/company\/conex-metals-india\/","https:\/\/www.instagram.com\/conexindia\/"]}]}},"_links":{"self":[{"href":"https:\/\/conexmetals.com\/es\/wp-json\/wp\/v2\/product\/26143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexmetals.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/conexmetals.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexmetals.com\/es\/wp-json\/wp\/v2\/media\/8727"}],"wp:attachment":[{"href":"https:\/\/conexmetals.com\/es\/wp-json\/wp\/v2\/media?parent=26143"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/conexmetals.com\/es\/wp-json\/wp\/v2\/product_brand?post=26143"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/conexmetals.com\/es\/wp-json\/wp\/v2\/product_cat?post=26143"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/conexmetals.com\/es\/wp-json\/wp\/v2\/product_tag?post=26143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}