{"id":25799,"date":"2024-01-17T12:26:40","date_gmt":"2024-01-17T06:56:40","guid":{"rendered":"https:\/\/conexmetals.com\/product\/din-7991-unc-type-hexagon-socket-countersunk-head-screw\/"},"modified":"2026-06-28T21:51:08","modified_gmt":"2026-06-28T16:21:08","slug":"vis-a-tete-fraisee-a-sixpans-creux-type-unc-din-7991","status":"publish","type":"product","link":"https:\/\/conexmetals.com\/fr\/product\/vis-a-tete-fraisee-a-sixpans-creux-type-unc-din-7991\/","title":{"rendered":"Vis \u00e0 T\u00eate Frais\u00e9e \u00e0 Sixpans Creux Type UNC DIN 7991"},"content":{"rendered":"\n<table id=\"tablepress-71\" class=\"tablepress tablepress-id-71 tbody-has-connected-cells\">\n<thead>\n<tr class=\"row-1\">\n\t<th colspan=\"8\" class=\"column-1\"><strong>DIN 7991 UNC-Type Hexagon Socket Countersunk Head Screw<\/strong><\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\"><strong>d<strong><sub>1<\/sub><\/strong><\/strong><\/td><td class=\"column-2\"><strong>d<strong><sub>2<\/sub><\/strong><\/strong><\/td><td class=\"column-3\"><strong>b<\/strong><\/td><td class=\"column-4\"><strong>k<\/strong><\/td><td class=\"column-5\"><strong>s<\/strong><\/td><td class=\"column-6\"><strong>n<\/strong><\/td><td class=\"column-7\"><strong> \u03b1<\/strong><\/td><td class=\"column-8\"><strong>L <strong>\u2264 <\/strong><strong><sup>1)<\/sup><\/strong><\/strong><\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">No. 4<\/td><td class=\"column-2\">6.4<\/td><td class=\"column-3\">19<\/td><td class=\"column-4\"> -<\/td><td class=\"column-5\">1 \/16\" 44<\/td><td class=\"column-6\">40<\/td><td class=\"column-7\">82\u00b0\u00b12<\/td><td class=\"column-8\">7\/8\"<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">No. 5<\/td><td class=\"column-2\">7.1<\/td><td class=\"column-3\">19<\/td><td class=\"column-4\">-<\/td><td class=\"column-5\">1\/64\" 44 <\/td><td class=\"column-6\">40<\/td><td class=\"column-7\">82\u00b0\u00b12<\/td><td class=\"column-8\">7\/8\"<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">No. 6<\/td><td class=\"column-2\">7.8<\/td><td class=\"column-3\">19<\/td><td class=\"column-4\">-<\/td><td class=\"column-5\">1\/64\" 33<\/td><td class=\"column-6\">32<\/td><td class=\"column-7\">82\u00b0\u00b12<\/td><td class=\"column-8\">7\/8\"<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\"><\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td><td class=\"column-5\"><\/td><td class=\"column-6\"><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td colspan=\"8\" class=\"column-1\"><strong>Conversion table: inches to millimeters<\/strong><\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\"><strong>inch<\/strong><\/td><td class=\"column-2\"><strong>inch dec.<\/strong><\/td><td class=\"column-3\"><strong>mm<\/strong><\/td><td class=\"column-4\"><strong>inch<\/strong><\/td><td class=\"column-5\"><strong>inch dec.<\/strong><\/td><td class=\"column-6\"><strong>mm<\/strong><\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">1\/64\"<\/td><td class=\"column-2\">1.5625E-2<\/td><td class=\"column-3\">0.397 <\/td><td class=\"column-4\">49\/64\"<\/td><td class=\"column-5\">0.765625<\/td><td class=\"column-6\">19.447<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">1\/32\"<\/td><td class=\"column-2\">3.125E-2<\/td><td class=\"column-3\">0.794 <\/td><td class=\"column-4\">25\/32\"<\/td><td class=\"column-5\">0.78125<\/td><td class=\"column-6\">19.844 <\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">3\/64\"<\/td><td class=\"column-2\">4.6875E-2<\/td><td class=\"column-3\">1.191 <\/td><td class=\"column-4\">51\/64\"<\/td><td class=\"column-5\">0.796875<\/td><td class=\"column-6\">20.241<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-12\">\n\t<td class=\"column-1\">1\/16'<\/td><td class=\"column-2\">6.25E-2<\/td><td class=\"column-3\">1.588 <\/td><td class=\"column-4\">13\/16\"<\/td><td class=\"column-5\">0.8125<\/td><td class=\"column-6\">20.638 <\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-13\">\n\t<td class=\"column-1\">5\/64\"<\/td><td class=\"column-2\">7.8125E-2<\/td><td class=\"column-3\">1.984<\/td><td class=\"column-4\">53\/64\"<\/td><td class=\"column-5\">0.828125<\/td><td class=\"column-6\">21.034<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-14\">\n\t<td class=\"column-1\">3\/32\"<\/td><td class=\"column-2\">9.375E-2<\/td><td class=\"column-3\">2.381<\/td><td class=\"column-4\">27\/32\"<\/td><td class=\"column-5\">0.84375<\/td><td class=\"column-6\">21.431 <\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-15\">\n\t<td class=\"column-1\">7\/64\"<\/td><td class=\"column-2\">0.109375<\/td><td class=\"column-3\">2.778<\/td><td class=\"column-4\">55\/64\"<\/td><td class=\"column-5\">0.859375<\/td><td class=\"column-6\">21.828<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-16\">\n\t<td class=\"column-1\">1\/8\"<\/td><td class=\"column-2\">0.125<\/td><td class=\"column-3\">3.175<\/td><td class=\"column-4\">7\/8\"<\/td><td class=\"column-5\">0.875<\/td><td class=\"column-6\">22.225 <\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-17\">\n\t<td class=\"column-1\">9\/64\"<\/td><td class=\"column-2\">0.140625<\/td><td class=\"column-3\">3.572 <\/td><td class=\"column-4\">57\/64\"<\/td><td class=\"column-5\">0.890625<\/td><td class=\"column-6\">22.622<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-18\">\n\t<td class=\"column-1\">5\/32\"<\/td><td class=\"column-2\">0.15625<\/td><td class=\"column-3\">3.969<\/td><td class=\"column-4\">29\/32\"<\/td><td class=\"column-5\">0.90625<\/td><td class=\"column-6\">23.019<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-19\">\n\t<td class=\"column-1\">11\/64\"<\/td><td class=\"column-2\">0.171875<\/td><td class=\"column-3\">4.366<\/td><td class=\"column-4\">59\/64\"<\/td><td class=\"column-5\">0.921875<\/td><td class=\"column-6\">23.416<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-20\">\n\t<td class=\"column-1\">3\/16\"<\/td><td class=\"column-2\">0.1875<\/td><td class=\"column-3\">4.762<\/td><td class=\"column-4\">15\/16\"<\/td><td class=\"column-5\">0.9375<\/td><td class=\"column-6\">23.812 <\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-21\">\n\t<td class=\"column-1\">13\/64\"<\/td><td class=\"column-2\">0.203125<\/td><td class=\"column-3\">5.159<\/td><td class=\"column-4\">61\/64\"<\/td><td class=\"column-5\">0.953125<\/td><td class=\"column-6\">24.209<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-22\">\n\t<td class=\"column-1\">7\/32\"<\/td><td class=\"column-2\">0.21875<\/td><td class=\"column-3\">5.556<\/td><td class=\"column-4\">31\/32\"<\/td><td class=\"column-5\">0.96875<\/td><td class=\"column-6\">24.607<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-23\">\n\t<td class=\"column-1\">15\/64\"<\/td><td class=\"column-2\">0.234375<\/td><td class=\"column-3\">5.953 <\/td><td class=\"column-4\">63\/64\"<\/td><td class=\"column-5\">0.984375<\/td><td class=\"column-6\">25.003<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-24\">\n\t<td class=\"column-1\">1\/4\"<\/td><td class=\"column-2\">0.25<\/td><td class=\"column-3\">6.35<\/td><td class=\"column-4\">1\"<\/td><td class=\"column-5\">1<\/td><td class=\"column-6\">25.4<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-25\">\n\t<td class=\"column-1\">17\/64\"<\/td><td class=\"column-2\">0.265625<\/td><td class=\"column-3\">6.747<\/td><td class=\"column-4\">1 1\/8\"<\/td><td class=\"column-5\">1.125<\/td><td class=\"column-6\">28.575<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-26\">\n\t<td class=\"column-1\">9\/32\"<\/td><td class=\"column-2\">0.28125<\/td><td class=\"column-3\">7.144 <\/td><td class=\"column-4\">1 1\/4\"<\/td><td class=\"column-5\">1.25<\/td><td class=\"column-6\">31.75<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-27\">\n\t<td class=\"column-1\">19\/64\"<\/td><td class=\"column-2\">0.296875<\/td><td class=\"column-3\">7.541 <\/td><td class=\"column-4\">1 3\/8\"<\/td><td class=\"column-5\">1.375<\/td><td class=\"column-6\">34.925<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-28\">\n\t<td class=\"column-1\">5\/16\"<\/td><td class=\"column-2\">0.3125<\/td><td class=\"column-3\">7.938<\/td><td class=\"column-4\">1 1\/2\"<\/td><td class=\"column-5\">1.5<\/td><td class=\"column-6\">38.1<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-29\">\n\t<td class=\"column-1\">21\/64\"<\/td><td class=\"column-2\">0.328125<\/td><td class=\"column-3\">8.334<\/td><td class=\"column-4\">1 5\/8\"<\/td><td class=\"column-5\">1.625<\/td><td class=\"column-6\">41.275<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-30\">\n\t<td class=\"column-1\">11\/32\"<\/td><td class=\"column-2\">0.34375<\/td><td class=\"column-3\">8.731<\/td><td class=\"column-4\">1 3\/4\"<\/td><td class=\"column-5\">1.75<\/td><td class=\"column-6\">44.45<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-31\">\n\t<td class=\"column-1\">23\/64\"<\/td><td class=\"column-2\">0.359375<\/td><td class=\"column-3\">9.128 <\/td><td class=\"column-4\">17\/8\"<\/td><td class=\"column-5\">1.875<\/td><td class=\"column-6\">47.625<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-32\">\n\t<td class=\"column-1\">3\/8\"<\/td><td class=\"column-2\">0.375<\/td><td class=\"column-3\">9.525 <\/td><td class=\"column-4\">2\"<\/td><td class=\"column-5\">2<\/td><td class=\"column-6\">50.8<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-33\">\n\t<td class=\"column-1\">25\/64\"<\/td><td class=\"column-2\">0.390625<\/td><td class=\"column-3\">9.922 <\/td><td class=\"column-4\">2 1\/4\"<\/td><td class=\"column-5\">2.25<\/td><td class=\"column-6\">57.15<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-34\">\n\t<td class=\"column-1\">13\/32\"<\/td><td class=\"column-2\">0.40625<\/td><td class=\"column-3\">10.319 <\/td><td class=\"column-4\">2 1\/2\"<\/td><td class=\"column-5\">2.5<\/td><td class=\"column-6\">63.5<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-35\">\n\t<td class=\"column-1\">27\/64\"<\/td><td class=\"column-2\">0.421875<\/td><td class=\"column-3\">10.716<\/td><td class=\"column-4\">2 3\/4\"<\/td><td class=\"column-5\">2.75<\/td><td class=\"column-6\">69.85<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-36\">\n\t<td class=\"column-1\">7\/16\"<\/td><td class=\"column-2\">0.4375<\/td><td class=\"column-3\">11.112<\/td><td class=\"column-4\">3\"<\/td><td class=\"column-5\">3<\/td><td class=\"column-6\">76.2<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-37\">\n\t<td class=\"column-1\">29\/64\"<\/td><td class=\"column-2\">0.453125<\/td><td class=\"column-3\">11.509<\/td><td class=\"column-4\">3 1\/4\"<\/td><td class=\"column-5\">3.25<\/td><td class=\"column-6\">82.55<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-38\">\n\t<td class=\"column-1\">15\/32\"<\/td><td class=\"column-2\">0.46875<\/td><td class=\"column-3\">11.906 <\/td><td class=\"column-4\">3 1\/2\"<\/td><td class=\"column-5\">3.5<\/td><td class=\"column-6\">88.9<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-39\">\n\t<td class=\"column-1\">31\/64\"<\/td><td class=\"column-2\">0.484375<\/td><td class=\"column-3\">12.303 <\/td><td class=\"column-4\">3 3\/4\"<\/td><td class=\"column-5\">3.75<\/td><td class=\"column-6\">95.25<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-40\">\n\t<td class=\"column-1\">1\/2\"<\/td><td class=\"column-2\">0.5<\/td><td class=\"column-3\">12.7<\/td><td class=\"column-4\">4\"<\/td><td class=\"column-5\">4<\/td><td class=\"column-6\">101.6<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-41\">\n\t<td class=\"column-1\">33\/64\"<\/td><td class=\"column-2\">0.515625<\/td><td class=\"column-3\">13.097<\/td><td class=\"column-4\">4 1\/4\"<\/td><td class=\"column-5\">4.25<\/td><td class=\"column-6\">107.95<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-42\">\n\t<td class=\"column-1\">17\/32\"<\/td><td class=\"column-2\">0.53125<\/td><td class=\"column-3\">13.494<\/td><td class=\"column-4\">4 1\/2\"<\/td><td class=\"column-5\">4.5<\/td><td class=\"column-6\">114.3<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-43\">\n\t<td class=\"column-1\">35\/64\"<\/td><td class=\"column-2\">0.546875<\/td><td class=\"column-3\">13.891<\/td><td class=\"column-4\">4 3\/4\"<\/td><td class=\"column-5\">4.75<\/td><td class=\"column-6\">120.65<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-44\">\n\t<td class=\"column-1\">9\/16\"<\/td><td class=\"column-2\">0.5625<\/td><td class=\"column-3\">14.288<\/td><td class=\"column-4\">5\"<\/td><td class=\"column-5\">5<\/td><td class=\"column-6\">127<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-45\">\n\t<td class=\"column-1\">37\/64\"<\/td><td class=\"column-2\">0.578125<\/td><td class=\"column-3\">14.684<\/td><td class=\"column-4\">5 1\/4\"<\/td><td class=\"column-5\">5.25<\/td><td class=\"column-6\">133.35<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-46\">\n\t<td class=\"column-1\">19\/32\"<\/td><td class=\"column-2\">0.59375<\/td><td class=\"column-3\">15.081<\/td><td class=\"column-4\">5 1\/2\"<\/td><td class=\"column-5\">5.5<\/td><td class=\"column-6\">139.7<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-47\">\n\t<td class=\"column-1\">39\/64\"<\/td><td class=\"column-2\">0.609375<\/td><td class=\"column-3\">15.478<\/td><td class=\"column-4\">5 3\/4\"<\/td><td class=\"column-5\">5.75<\/td><td class=\"column-6\">146.05 <\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-48\">\n\t<td class=\"column-1\">5\/8\"<\/td><td class=\"column-2\">0.625<\/td><td class=\"column-3\">15.875<\/td><td class=\"column-4\">6\"<\/td><td class=\"column-5\">6<\/td><td class=\"column-6\">152.4<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-49\">\n\t<td class=\"column-1\">41\/64\"<\/td><td class=\"column-2\">0.640625<\/td><td class=\"column-3\">16.272<\/td><td class=\"column-4\">6 1\/2\"<\/td><td class=\"column-5\">6.5<\/td><td class=\"column-6\">165.1<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-50\">\n\t<td class=\"column-1\">21\/32\"<\/td><td class=\"column-2\">0.65625<\/td><td class=\"column-3\">16.669<\/td><td class=\"column-4\">7\"<\/td><td class=\"column-5\">7<\/td><td class=\"column-6\">177.8<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-51\">\n\t<td class=\"column-1\">43\/64\"<\/td><td class=\"column-2\">0.671875<\/td><td class=\"column-3\">17.066<\/td><td class=\"column-4\">7 112\"<\/td><td class=\"column-5\">7.5<\/td><td class=\"column-6\">190.5<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-52\">\n\t<td class=\"column-1\">11\/16\"<\/td><td class=\"column-2\">0.6875<\/td><td class=\"column-3\">17.462<\/td><td class=\"column-4\">8\"<\/td><td class=\"column-5\">8<\/td><td class=\"column-6\">203.2<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-53\">\n\t<td class=\"column-1\">45\/64\"<\/td><td class=\"column-2\">0.703125<\/td><td class=\"column-3\">17.859 <\/td><td class=\"column-4\">8 1\/2\"<\/td><td class=\"column-5\">8.5<\/td><td class=\"column-6\">215.9<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-54\">\n\t<td class=\"column-1\">23\/32\"<\/td><td class=\"column-2\">0.71875<\/td><td class=\"column-3\">18.256<\/td><td class=\"column-4\">9\"<\/td><td class=\"column-5\">9<\/td><td class=\"column-6\">228.6<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-55\">\n\t<td class=\"column-1\">47\/64\"<\/td><td class=\"column-2\">0.734375<\/td><td class=\"column-3\">18.653<\/td><td class=\"column-4\">9 1\/2\"<\/td><td class=\"column-5\">9.5<\/td><td class=\"column-6\">241.3<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<tr class=\"row-56\">\n\t<td class=\"column-1\">3\/4\"<\/td><td class=\"column-2\">0.75<\/td><td class=\"column-3\">19.05<\/td><td class=\"column-4\">10\"<\/td><td class=\"column-5\">10<\/td><td class=\"column-6\">254<\/td><td class=\"column-7\"><\/td><td class=\"column-8\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-71 from cache -->\n","protected":false},"excerpt":{"rendered":"[table id=71 \/]\n","protected":false},"featured_media":25789,"template":"","meta":[],"product_brand":[],"product_cat":[632],"product_tag":[],"class_list":{"0":"post-25799","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-produits","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vis \u00e0 T\u00eate Frais\u00e9e \u00e0 Sixpans Creux Type UNC DIN 7991<\/title>\n<meta name=\"description\" content=\"Conex Metals, a global leader in metal manufacturing and export for 34 years, delivers excellence worldwide. Specializing in high-quality non-ferrous metal components such as Brass Fittings, Brass Parts, Copper Parts, and Brass Plumbing Fittings. Experience precision and innovation with Conex Metals.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/conexmetals.com\/fr\/product\/vis-a-tete-fraisee-a-sixpans-creux-type-unc-din-7991\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/conexmetals.com\\\/fr\\\/product\\\/vis-a-tete-fraisee-a-sixpans-creux-type-unc-din-7991\\\/\",\"url\":\"https:\\\/\\\/conexmetals.com\\\/fr\\\/product\\\/vis-a-tete-fraisee-a-sixpans-creux-type-unc-din-7991\\\/\",\"name\":\"Vis \u00e0 T\u00eate Frais\u00e9e \u00e0 Sixpans Creux Type UNC DIN 7991\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/conexmetals.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/conexmetals.com\\\/fr\\\/product\\\/vis-a-tete-fraisee-a-sixpans-creux-type-unc-din-7991\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/conexmetals.com\\\/fr\\\/product\\\/vis-a-tete-fraisee-a-sixpans-creux-type-unc-din-7991\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/conexmetals.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/7991.gif\",\"datePublished\":\"2024-01-17T06:56:40+00:00\",\"dateModified\":\"2026-06-28T16:21:08+00:00\",\"description\":\"Conex Metals, a global leader in metal manufacturing and export for 34 years, delivers excellence worldwide. Specializing in high-quality non-ferrous metal components such as Brass Fittings, Brass Parts, Copper Parts, and Brass Plumbing Fittings. Experience precision and innovation with Conex Metals.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/conexmetals.com\\\/fr\\\/product\\\/vis-a-tete-fraisee-a-sixpans-creux-type-unc-din-7991\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/conexmetals.com\\\/fr\\\/product\\\/vis-a-tete-fraisee-a-sixpans-creux-type-unc-din-7991\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/conexmetals.com\\\/fr\\\/product\\\/vis-a-tete-fraisee-a-sixpans-creux-type-unc-din-7991\\\/#primaryimage\",\"url\":\"https:\\\/\\\/conexmetals.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/7991.gif\",\"contentUrl\":\"https:\\\/\\\/conexmetals.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/7991.gif\",\"width\":400,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/conexmetals.com\\\/fr\\\/product\\\/vis-a-tete-fraisee-a-sixpans-creux-type-unc-din-7991\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/conexmetals.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/conexmetals.com\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vis \u00e0 T\u00eate Frais\u00e9e \u00e0 Sixpans Creux Type UNC DIN 7991\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/conexmetals.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/conexmetals.com\\\/fr\\\/\",\"name\":\"Conex Metals Brass Fittings Brass Parts Copper Parts Brass Components Brass Plumbing Fittings India\",\"description\":\"Manufacturer of Bronze Fittings casting Copper Brass parts components\",\"publisher\":{\"@id\":\"https:\\\/\\\/conexmetals.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/conexmetals.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/conexmetals.com\\\/fr\\\/#organization\",\"name\":\"Conex Metals\",\"url\":\"https:\\\/\\\/conexmetals.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/conexmetals.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/conexmetals.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/conex-metals-logo.webp\",\"contentUrl\":\"https:\\\/\\\/conexmetals.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/conex-metals-logo.webp\",\"width\":300,\"height\":121,\"caption\":\"Conex Metals\"},\"image\":{\"@id\":\"https:\\\/\\\/conexmetals.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/conexbrass\",\"https:\\\/\\\/x.com\\\/conexindia\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/conex-metals-india\\\/\",\"https:\\\/\\\/www.instagram.com\\\/conexindia\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vis \u00e0 T\u00eate Frais\u00e9e \u00e0 Sixpans Creux Type UNC DIN 7991","description":"Conex Metals, a global leader in metal manufacturing and export for 34 years, delivers excellence worldwide. Specializing in high-quality non-ferrous metal components such as Brass Fittings, Brass Parts, Copper Parts, and Brass Plumbing Fittings. Experience precision and innovation with Conex Metals.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/conexmetals.com\/fr\/product\/vis-a-tete-fraisee-a-sixpans-creux-type-unc-din-7991\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/conexmetals.com\/fr\/product\/vis-a-tete-fraisee-a-sixpans-creux-type-unc-din-7991\/","url":"https:\/\/conexmetals.com\/fr\/product\/vis-a-tete-fraisee-a-sixpans-creux-type-unc-din-7991\/","name":"Vis \u00e0 T\u00eate Frais\u00e9e \u00e0 Sixpans Creux Type UNC DIN 7991","isPartOf":{"@id":"https:\/\/conexmetals.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/conexmetals.com\/fr\/product\/vis-a-tete-fraisee-a-sixpans-creux-type-unc-din-7991\/#primaryimage"},"image":{"@id":"https:\/\/conexmetals.com\/fr\/product\/vis-a-tete-fraisee-a-sixpans-creux-type-unc-din-7991\/#primaryimage"},"thumbnailUrl":"https:\/\/conexmetals.com\/wp-content\/uploads\/2023\/12\/7991.gif","datePublished":"2024-01-17T06:56:40+00:00","dateModified":"2026-06-28T16:21:08+00:00","description":"Conex Metals, a global leader in metal manufacturing and export for 34 years, delivers excellence worldwide. Specializing in high-quality non-ferrous metal components such as Brass Fittings, Brass Parts, Copper Parts, and Brass Plumbing Fittings. Experience precision and innovation with Conex Metals.","breadcrumb":{"@id":"https:\/\/conexmetals.com\/fr\/product\/vis-a-tete-fraisee-a-sixpans-creux-type-unc-din-7991\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/conexmetals.com\/fr\/product\/vis-a-tete-fraisee-a-sixpans-creux-type-unc-din-7991\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/conexmetals.com\/fr\/product\/vis-a-tete-fraisee-a-sixpans-creux-type-unc-din-7991\/#primaryimage","url":"https:\/\/conexmetals.com\/wp-content\/uploads\/2023\/12\/7991.gif","contentUrl":"https:\/\/conexmetals.com\/wp-content\/uploads\/2023\/12\/7991.gif","width":400,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/conexmetals.com\/fr\/product\/vis-a-tete-fraisee-a-sixpans-creux-type-unc-din-7991\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/conexmetals.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/conexmetals.com\/products\/"},{"@type":"ListItem","position":3,"name":"Vis \u00e0 T\u00eate Frais\u00e9e \u00e0 Sixpans Creux Type UNC DIN 7991"}]},{"@type":"WebSite","@id":"https:\/\/conexmetals.com\/fr\/#website","url":"https:\/\/conexmetals.com\/fr\/","name":"Conex Metals Brass Fittings Brass Parts Copper Parts Brass Components Brass Plumbing Fittings India","description":"Manufacturer of Bronze Fittings casting Copper Brass parts components","publisher":{"@id":"https:\/\/conexmetals.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/conexmetals.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/conexmetals.com\/fr\/#organization","name":"Conex Metals","url":"https:\/\/conexmetals.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/conexmetals.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/conexmetals.com\/wp-content\/uploads\/2024\/03\/conex-metals-logo.webp","contentUrl":"https:\/\/conexmetals.com\/wp-content\/uploads\/2024\/03\/conex-metals-logo.webp","width":300,"height":121,"caption":"Conex Metals"},"image":{"@id":"https:\/\/conexmetals.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/conexbrass","https:\/\/x.com\/conexindia","https:\/\/www.linkedin.com\/company\/conex-metals-india\/","https:\/\/www.instagram.com\/conexindia\/"]}]}},"_links":{"self":[{"href":"https:\/\/conexmetals.com\/fr\/wp-json\/wp\/v2\/product\/25799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conexmetals.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/conexmetals.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conexmetals.com\/fr\/wp-json\/wp\/v2\/media\/25789"}],"wp:attachment":[{"href":"https:\/\/conexmetals.com\/fr\/wp-json\/wp\/v2\/media?parent=25799"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/conexmetals.com\/fr\/wp-json\/wp\/v2\/product_brand?post=25799"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/conexmetals.com\/fr\/wp-json\/wp\/v2\/product_cat?post=25799"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/conexmetals.com\/fr\/wp-json\/wp\/v2\/product_tag?post=25799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}